{"id":7013,"date":"2017-09-04T19:49:06","date_gmt":"2017-09-04T19:49:06","guid":{"rendered":"https:\/\/logifarma.yourcode-staging.com\/magazine-blog-landing\/"},"modified":"2024-07-15T15:44:23","modified_gmt":"2024-07-15T15:44:23","slug":"magazine-blog-landing","status":"publish","type":"page","link":"https:\/\/alloga-logifarma.pt\/en\/","title":{"rendered":"Homepage"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;5939&#8243; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; full_height=&#8221;yes&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;4%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;medium&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column left_padding_desktop=&#8221;10%&#8221; right_padding_desktop=&#8221;40%&#8221; left_padding_tablet=&#8221;10%&#8221; constrain_group_103=&#8221;yes&#8221; right_padding_tablet=&#8221;10%&#8221; left_padding_phone=&#8221;10%&#8221; constrain_group_105=&#8221;yes&#8221; right_padding_phone=&#8221;10%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;rotateButtonDown&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;The right Logistics for Health&#8221; font_container=&#8221;tag:h1|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;25px&#8221;][image_with_animation image_url=&#8221;6126&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;custom&#8221; max_width_custom=&#8221;100%&#8221; max_width_custom_phone=&#8221;50%&#8221; el_class=&#8221;greenButton pointer&#8221; img_link=&#8221;#valores_anuais&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;10%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;10%&#8221; top_margin=&#8221;5%&#8221; constrain_group_7=&#8221;yes&#8221; bottom_margin=&#8221;5%&#8221; top_margin_tablet=&#8221;10%&#8221; top_margin_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;valores_anuais&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;7104&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Bottom&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;custom&#8221; max_width_custom=&#8221;70%&#8221; max_width_custom_tablet=&#8221;100%&#8221; max_width_custom_phone=&#8221;100%&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;custom&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; left_padding_desktop=&#8221;10%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;temButtonBranco&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-left&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;A pre-wholesaler company with more than 26 years of operation, dedicated exclusively to pharmaceutical logistics&#8221; font_container=&#8221;tag:h3|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;25px&#8221; custom_height_tablet=&#8221;25px&#8221; custom_height_phone=&#8221;25px&#8221;][vc_custom_heading text=&#8221;We belong to the European Alloga Network which allows us to provide a set of advantages for our clients: from sharing internationally validated practices, that we import to our clients in Portugal, to the standardization and integration of European operations for our international clients.<\/p>\n<p>We operate in our own set of modern and efficient infrastructures, with a high degree of automation.<\/p>\n<p>Our Quality and Security teams ensure we fulfil the most demanding market requirements.&#8221; font_container=&#8221;tag:p|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;see-through-2&#8243; hover_color_override=&#8221;#005aff&#8221; hover_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;none&#8221; text=&#8221;Contacts&#8221; css_animation=&#8221;none&#8221; url=&#8221;\/en\/contactos\/&#8221;][\/vc_column][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;minimum&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;0px&#8221; custom_height_tablet=&#8221;50px&#8221; custom_height_phone=&#8221;50px&#8221;][image_with_animation image_url=&#8221;6657&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;right&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; el_class=&#8221;somosUmaEmpresa&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;0px&#8221; custom_height_tablet=&#8221;50px&#8221; custom_height_phone=&#8221;50px&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_2=&#8221;yes&#8221; top_margin=&#8221;5%&#8221; top_margin_tablet=&#8221;10%&#8221; top_margin_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column left_padding_desktop=&#8221;20%&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;20%&#8221; left_padding_tablet=&#8221;10%&#8221; constrain_group_103=&#8221;yes&#8221; right_padding_tablet=&#8221;10%&#8221; left_padding_phone=&#8221;10%&#8221; right_padding_phone=&#8221;10%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#005aff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;temButtonAzul&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-left&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;medium_fast&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;50px&#8221; custom_height_tablet=&#8221;50px&#8221; custom_height_phone=&#8221;50px&#8221;][vc_custom_heading text=&#8221;The right Service&#8221; font_container=&#8221;tag:h3|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_custom_heading text=&#8221;We provide services to +120 clients, from all market segments, to whom we offer a complete portfolio of services.&#8221; font_container=&#8221;tag:p|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;see-through-2&#8243; hover_color_override=&#8221;#ffffff&#8221; hover_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;none&#8221; text=&#8221;About us&#8221; css_animation=&#8221;none&#8221; url=&#8221;\/en\/a-alloga-logifarma\/&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;50px&#8221; custom_height_tablet=&#8221;50px&#8221; custom_height_phone=&#8221;50px&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;7097&#8243; background_image_position=&#8221;left center&#8221; background_image_stacking=&#8221;default&#8221; background_image_loading=&#8221;default&#8221; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-right&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;very_subtle&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;10%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;10%&#8221; constrain_group_7=&#8221;yes&#8221; bottom_margin_tablet=&#8221;5%&#8221; bottom_margin_phone=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; translate_y=&#8221;-50%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;rotateButtonDown&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;6126&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;custom&#8221; max_width_custom=&#8221;80%&#8221; el_class=&#8221;greenButton&#8221; img_link=&#8221;#servicos&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;30px&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;10%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;10%&#8221; top_margin=&#8221;5%&#8221; top_margin_tablet=&#8221;0%&#8221; constrain_group_9=&#8221;yes&#8221; bottom_margin_tablet=&#8221;0%&#8221; top_margin_phone=&#8221;0%&#8221; constrain_group_11=&#8221;yes&#8221; bottom_margin_phone=&#8221;0%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;servicos&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;6541&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Left&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;25px&#8221;][vc_custom_heading text=&#8221;Logistics&#8221; font_container=&#8221;tag:h4|text_align:center|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_custom_heading text=&#8221;Operating from modern and technologically advanced facilities, we offer a global approach to respond to our customers&#8217; needs, seeking to offer tailor-made solutions.&#8221; font_container=&#8221;tag:p|text_align:center|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;0px&#8221; custom_height_tablet=&#8221;50px&#8221; custom_height_phone=&#8221;50px&#8221;][\/vc_column][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;6540&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Bottom&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;25px&#8221;][vc_custom_heading text=&#8221;Added Value&#8221; font_container=&#8221;tag:h4|text_align:center|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_custom_heading text=&#8221;Relying on a unique know-how based on many years of experience, flexibility and efficiency, we&#8217;re permanently looking for new solutions and answers for the needs and expectations of our customers, adding even more value to their business.&#8221; font_container=&#8221;tag:p|text_align:center|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;0px&#8221; custom_height_tablet=&#8221;50px&#8221; custom_height_phone=&#8221;50px&#8221;][\/vc_column][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;6542&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Right&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;25px&#8221;][vc_custom_heading text=&#8221;Client Relationship&#8221; font_container=&#8221;tag:h4|text_align:center|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_custom_heading text=&#8221;Our operational, customer service and customer support teams are dedicated to providing high quality and rigorous services, maintaining a strong commitment and focus on customer needs.&#8221; font_container=&#8221;tag:p|text_align:center|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;0px&#8221; custom_height_tablet=&#8221;50px&#8221; custom_height_phone=&#8221;50px&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;10%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;10%&#8221; bottom_margin=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;temButtonBranco&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;see-through-2&#8243; hover_color_override=&#8221;#005aff&#8221; hover_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;none&#8221; text=&#8221;Services&#8221; css_animation=&#8221;none&#8221; url=&#8221;\/en\/servicos\/&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;0px&#8221; custom_height_tablet=&#8221;50px&#8221; custom_height_phone=&#8221;50px&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#005aff&#8221; scene_position=&#8221;center&#8221; top_margin=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;6875&#8243; background_image_position=&#8221;center center&#8221; background_image_stacking=&#8221;default&#8221; background_image_loading=&#8221;default&#8221; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-lg vc_hidden-md&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;50px&#8221; custom_height_tablet=&#8221;50px&#8221; custom_height_phone=&#8221;50px&#8221;][image_with_animation image_url=&#8221;7108&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;custom&#8221; max_width_custom=&#8221;45%&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;50px&#8221; custom_height_tablet=&#8221;50px&#8221; custom_height_phone=&#8221;50px&#8221;][\/vc_column][vc_column left_padding_desktop=&#8221;20%&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;20%&#8221; left_padding_tablet=&#8221;10%&#8221; constrain_group_103=&#8221;yes&#8221; right_padding_tablet=&#8221;10%&#8221; left_padding_phone=&#8221;10%&#8221; constrain_group_105=&#8221;yes&#8221; right_padding_phone=&#8221;10%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;temButtonAzul&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-lg vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;0px&#8221; custom_height_tablet=&#8221;50px&#8221; custom_height_phone=&#8221;50px&#8221;][vc_custom_heading text=&#8221;The right infrastructure for the right distribution&#8221; font_container=&#8221;tag:h3|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;25px&#8221;][vc_custom_heading text=&#8221;- Modern and technologically advanced facilties<br \/>\n&#8211; Own fleet<br \/>\n&#8211; Complete national coverage<br \/>\n&#8211; Customizable, in-house developed, softwares<br \/>\n&#8211; Real-time information available&#8221; font_container=&#8221;tag:p|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;see-through-2&#8243; hover_color_override=&#8221;#ffffff&#8221; hover_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;buttonTransparenteBordaBranco&#8221; text=&#8221;Contacts&#8221; css_animation=&#8221;none&#8221; url=&#8221;\/en\/contactos\/&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;0px&#8221; custom_height_tablet=&#8221;50px&#8221; custom_height_phone=&#8221;50px&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#005aff&#8221; scene_position=&#8221;center&#8221; top_margin=&#8221;5%&#8221; constrain_group_7=&#8221;yes&#8221; bottom_margin=&#8221;5%&#8221; top_margin_phone=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;6538&#8243; background_image_position=&#8221;center center&#8221; background_image_stacking=&#8221;default&#8221; background_image_loading=&#8221;default&#8221; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-left&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;very_subtle&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;50px&#8221; custom_height_tablet=&#8221;50px&#8221; custom_height_phone=&#8221;50px&#8221;][image_with_animation image_url=&#8221;7108&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;right&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;custom&#8221; translate_x_desktop=&#8221;12%&#8221; max_width_custom=&#8221;25%&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;50px&#8221; custom_height_tablet=&#8221;50px&#8221; custom_height_phone=&#8221;50px&#8221;][\/vc_column][vc_column left_padding_desktop=&#8221;20%&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;20%&#8221; left_padding_tablet=&#8221;10%&#8221; constrain_group_103=&#8221;yes&#8221; right_padding_tablet=&#8221;10%&#8221; left_padding_phone=&#8221;10%&#8221; constrain_group_105=&#8221;yes&#8221; right_padding_phone=&#8221;10%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;temButtonAzul&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-right&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;50px&#8221; custom_height_tablet=&#8221;50px&#8221; custom_height_phone=&#8221;50px&#8221;][vc_custom_heading text=&#8221;The right infrastructure for the right distribution&#8221; font_container=&#8221;tag:h3|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;25px&#8221;][vc_custom_heading text=&#8221;- Modern and technologically advanced facilties<br \/>\n&#8211; Own fleet<br \/>\n&#8211; Complete national coverage<br \/>\n&#8211; Customizable, in-house developed, softwares<br \/>\n&#8211; Real-time information available&#8221; font_container=&#8221;tag:p|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;see-through-2&#8243; hover_color_override=&#8221;#ffffff&#8221; hover_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;buttonTransparenteBordaBranco&#8221; text=&#8221;Contacts&#8221; css_animation=&#8221;none&#8221; url=&#8221;\/en\/contactos\/&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;50px&#8221; custom_height_tablet=&#8221;50px&#8221; custom_height_phone=&#8221;50px&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;10%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;10%&#8221; top_margin=&#8221;10%&#8221; bottom_margin=&#8221;2%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;We guarantee the right Quality&#8221; font_container=&#8221;tag:h3|text_align:center|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_2=&#8221;yes&#8221; top_margin=&#8221;5%&#8221; bottom_margin=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; delay=&#8221;0&#8243;][image_with_animation image_url=&#8221;7341&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; delay=&#8221;100&#8243;][image_with_animation image_url=&#8221;6082&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; delay=&#8221;200&#8243;][image_with_animation image_url=&#8221;6081&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; delay=&#8221;300&#8243;][image_with_animation image_url=&#8221;6085&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; delay=&#8221;400&#8243;][image_with_animation image_url=&#8221;6083&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; delay=&#8221;500&#8243;][image_with_animation image_url=&#8221;6080&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#005aff&#8221; scene_position=&#8221;center&#8221; top_margin=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column left_padding_desktop=&#8221;20%&#8221; constrain_group_101=&#8221;yes&#8221; right_padding_desktop=&#8221;20%&#8221; left_padding_tablet=&#8221;10%&#8221; constrain_group_103=&#8221;yes&#8221; right_padding_tablet=&#8221;10%&#8221; left_padding_phone=&#8221;10%&#8221; constrain_group_105=&#8221;yes&#8221; right_padding_phone=&#8221;10%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;temButtonBranco temButtonVerde&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-left&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;0px&#8221; custom_height_tablet=&#8221;50px&#8221; custom_height_phone=&#8221;50px&#8221;][nectar_btn size=&#8221;jumbo&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-1&#8243; icon_family=&#8221;none&#8221; el_class=&#8221;logisticaCerta&#8221; text=&#8221;The Right Logistics&#8221; css_animation=&#8221;none&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;25px&#8221; custom_height_tablet=&#8221;50px&#8221; custom_height_phone=&#8221;50px&#8221;][vc_custom_heading text=&#8221;Because in health we want<br \/>\neverything to be right!&#8221; font_container=&#8221;tag:h4|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;25px&#8221; custom_height_tablet=&#8221;50px&#8221; custom_height_phone=&#8221;50px&#8221;][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;see-through-2&#8243; hover_color_override=&#8221;#0bd880&#8243; hover_text_color_override=&#8221;#000000&#8243; icon_family=&#8221;none&#8221; text=&#8221;Contacts&#8221; css_animation=&#8221;none&#8221; url=&#8221;\/en\/contactos\/&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;0px&#8221; custom_height_tablet=&#8221;50px&#8221; custom_height_phone=&#8221;50px&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-right&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;6087&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;right&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;5939&#8243; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; full_height=&#8221;yes&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;4%&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-7013","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.9.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Homepage - Logifarma<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/alloga-logifarma.pt\/en\/\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Homepage - Logifarma\" \/>\r\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;5939&#8243; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; full_height=&#8221;yes&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;4%&#8221;...\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/alloga-logifarma.pt\/en\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Logifarma\" \/>\r\n<meta property=\"article:modified_time\" content=\"2024-07-15T15:44:23+00:00\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutes\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/alloga-logifarma.pt\/en\/\",\"url\":\"https:\/\/alloga-logifarma.pt\/en\/\",\"name\":\"Homepage - Logifarma\",\"isPartOf\":{\"@id\":\"https:\/\/alloga-logifarma.pt\/#website\"},\"datePublished\":\"2017-09-04T19:49:06+00:00\",\"dateModified\":\"2024-07-15T15:44:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/alloga-logifarma.pt\/en\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/alloga-logifarma.pt\/en\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/alloga-logifarma.pt\/en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/alloga-logifarma.pt\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Homepage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/alloga-logifarma.pt\/#website\",\"url\":\"https:\/\/alloga-logifarma.pt\/\",\"name\":\"Alloga Logifarma\",\"description\":\"Somos uma empresa pr\u00e9-grossista, com mais de 26 anos de opera\u00e7\u00e3o, dedicada em exclusivo \u00e0 log\u00edstica da Sa\u00fade\",\"publisher\":{\"@id\":\"https:\/\/alloga-logifarma.pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/alloga-logifarma.pt\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/alloga-logifarma.pt\/#organization\",\"name\":\"Alloga Logifarma\",\"url\":\"https:\/\/alloga-logifarma.pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/alloga-logifarma.pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/alloga-logifarma.pt\/wp-content\/uploads\/2023\/06\/ALLOGA_LOGIGARMA.svg\",\"contentUrl\":\"https:\/\/alloga-logifarma.pt\/wp-content\/uploads\/2023\/06\/ALLOGA_LOGIGARMA.svg\",\"width\":1465,\"height\":420,\"caption\":\"Alloga Logifarma\"},\"image\":{\"@id\":\"https:\/\/alloga-logifarma.pt\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/alloga-logifarma\/\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Homepage - Logifarma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alloga-logifarma.pt\/en\/","og_locale":"en_US","og_type":"article","og_title":"Homepage - Logifarma","og_description":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;5939&#8243; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; full_height=&#8221;yes&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;4%&#8221;...","og_url":"https:\/\/alloga-logifarma.pt\/en\/","og_site_name":"Logifarma","article_modified_time":"2024-07-15T15:44:23+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alloga-logifarma.pt\/en\/","url":"https:\/\/alloga-logifarma.pt\/en\/","name":"Homepage - Logifarma","isPartOf":{"@id":"https:\/\/alloga-logifarma.pt\/#website"},"datePublished":"2017-09-04T19:49:06+00:00","dateModified":"2024-07-15T15:44:23+00:00","breadcrumb":{"@id":"https:\/\/alloga-logifarma.pt\/en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alloga-logifarma.pt\/en\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/alloga-logifarma.pt\/en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/alloga-logifarma.pt\/en\/"},{"@type":"ListItem","position":2,"name":"Homepage"}]},{"@type":"WebSite","@id":"https:\/\/alloga-logifarma.pt\/#website","url":"https:\/\/alloga-logifarma.pt\/","name":"Alloga Logifarma","description":"Somos uma empresa pr\u00e9-grossista, com mais de 26 anos de opera\u00e7\u00e3o, dedicada em exclusivo \u00e0 log\u00edstica da Sa\u00fade","publisher":{"@id":"https:\/\/alloga-logifarma.pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alloga-logifarma.pt\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/alloga-logifarma.pt\/#organization","name":"Alloga Logifarma","url":"https:\/\/alloga-logifarma.pt\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/alloga-logifarma.pt\/#\/schema\/logo\/image\/","url":"https:\/\/alloga-logifarma.pt\/wp-content\/uploads\/2023\/06\/ALLOGA_LOGIGARMA.svg","contentUrl":"https:\/\/alloga-logifarma.pt\/wp-content\/uploads\/2023\/06\/ALLOGA_LOGIGARMA.svg","width":1465,"height":420,"caption":"Alloga Logifarma"},"image":{"@id":"https:\/\/alloga-logifarma.pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/alloga-logifarma\/"]}]}},"_links":{"self":[{"href":"https:\/\/alloga-logifarma.pt\/en\/wp-json\/wp\/v2\/pages\/7013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alloga-logifarma.pt\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alloga-logifarma.pt\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alloga-logifarma.pt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alloga-logifarma.pt\/en\/wp-json\/wp\/v2\/comments?post=7013"}],"version-history":[{"count":16,"href":"https:\/\/alloga-logifarma.pt\/en\/wp-json\/wp\/v2\/pages\/7013\/revisions"}],"predecessor-version":[{"id":7346,"href":"https:\/\/alloga-logifarma.pt\/en\/wp-json\/wp\/v2\/pages\/7013\/revisions\/7346"}],"wp:attachment":[{"href":"https:\/\/alloga-logifarma.pt\/en\/wp-json\/wp\/v2\/media?parent=7013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}